{"id":61,"date":"2021-08-14T15:28:08","date_gmt":"2021-08-14T13:28:08","guid":{"rendered":"http:\/\/www.chambres-hote-aveyron.com\/?page_id=61"},"modified":"2022-07-26T17:07:41","modified_gmt":"2022-07-26T15:07:41","slug":"chambre-dune","status":"publish","type":"page","link":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/","title":{"rendered":"Chambre Dune"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"960\" data-id=\"1488\" src=\"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg\" alt=\"\" class=\"wp-image-1488\" srcset=\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg 720w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"134\" src=\"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-1024x768.jpg\" alt=\"\" class=\"wp-image-134\" srcset=\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-1024x768.jpg 1024w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-300x225.jpg 300w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-768x576.jpg 768w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-1536x1152.jpg 1536w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-960x720.jpg 960w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-620x465.jpg 620w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156-400x300.jpg 400w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/IMG_20210419_105156.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"720\" data-id=\"1490\" src=\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/IMG_1465-2.jpg\" alt=\"\" class=\"wp-image-1490\" srcset=\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/IMG_1465-2.jpg 960w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/IMG_1465-2-300x225.jpg 300w, https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/IMG_1465-2-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Chambre tout confort avec salle d&rsquo;eau.<br>Double vasque et douche \u00e0 l&rsquo;italienne.<\/p>\n\n\n\n<p>Tarif : 60\u20ac \/ nuit<br>Petit-d\u00e9jeuner : 10\u20ac<br>Diner : sur r\u00e9servation<\/p>\n\n\n<div class=\"wpsbc-container wpsbc-calendar-1\" data-id=\"1\" data-show_title=\"0\" data-months_to_show=\"1\" data-start_weekday=\"1\" data-show_legend=\"1\" data-legend_position=\"side\" data-show_button_navigation=\"1\" data-show_selector_navigation=\"1\" data-show_week_numbers=\"0\" data-current_year=\"2026\" data-current_month=\"7\" data-jump_months=\"0\" data-highlight_today=\"0\" data-history=\"1\" data-show_tooltip=\"1\" data-language=\"fr\" data-min_width=\"200\" data-max_width=\"380\" ><div class=\"wpsbc-calendars-wrapper wpsbc-legend-position-side\"><div class=\"wpsbc-legend\"><div class=\"wpsbc-legend-item\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><span class=wpsbc-legend-item-name>Disponible<\/span><\/div><div class=\"wpsbc-legend-item\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-2\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><span class=wpsbc-legend-item-name>R\u00e9serv\u00e9<\/span><\/div><div class=\"wpsbc-legend-item\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-3\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><span class=wpsbc-legend-item-name>Passage<\/span><\/div><\/div><div class=\"wpsbc-calendars\"><div class=\"wpsbc-calendar\"><div class=\"wpsbc-calendar-header wpsbc-heading\"><div class=\"wpsbc-calendar-header-navigation\"><a href=\"#\" class=\"wpsbc-prev\" aria-label=\"Navigate to Previous Month\"><span class=\"wpsbc-arrow\"><\/span><\/a><div class=\"wpsbc-select-container\"><select aria-label=\"Month Selector\"><option value=\"1776211200\" >Avril 2026<\/option><option value=\"1778803200\" >Mai 2026<\/option><option value=\"1781481600\" >Juin 2026<\/option><option value=\"1784073600\"  selected='selected'>Juillet 2026<\/option><option value=\"1786752000\" >Ao\u00fbt 2026<\/option><option value=\"1789430400\" >Septembre 2026<\/option><option value=\"1792022400\" >Octobre 2026<\/option><option value=\"1794700800\" >Novembre 2026<\/option><option value=\"1797292800\" >D\u00e9cembre 2026<\/option><option value=\"1799971200\" >Janvier 2027<\/option><option value=\"1802649600\" >F\u00e9vrier 2027<\/option><option value=\"1805068800\" >Mars 2027<\/option><option value=\"1807747200\" >Avril 2027<\/option><option value=\"1810339200\" >Mai 2027<\/option><option value=\"1813017600\" >Juin 2027<\/option><option value=\"1815609600\" >Juillet 2027<\/option><\/select><\/div><a href=\"#\" class=\"wpsbc-next\" aria-label=\"Navigate to Next Month\"><span class=\"wpsbc-arrow\"><\/span><\/a><\/div><\/div><div class=\"wpsbc-calendar-wrapper\"><table><thead><tr><th>L<\/th><th>M<\/th><th>M<\/th><th>J<\/th><th>V<\/th><th>S<\/th><th>D<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpsbc-date   wpsbc-gap \" ><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \" ><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"1\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"2\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"3\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"4\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"5\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">5<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"6\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"7\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"8\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"9\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"10\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"11\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"12\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">12<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"13\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"14\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"15\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"16\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"17\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"18\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"19\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">19<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"20\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"21\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"22\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"23\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"24\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"25\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"26\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">26<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"27\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"28\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"29\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"30\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-1   \" data-year=\"2026\" data-month=\"7\" data-day=\"31\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-1\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\" ><\/div><div class=\"wpsbc-legend-item-icon-color\" ><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">31<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \" ><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \" ><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><style>.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-1 div:first-of-type { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-1 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-1 div:first-of-type svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-1 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-ical-changeover .wpsbc-legend-item-icon:after {background-color: #ddffcc;}.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-2 div:first-of-type { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-2 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-2 div:first-of-type svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-2 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-3 div:first-of-type { background-color: #fee2a0 !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-3 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-3 div:first-of-type svg { fill: #fee2a0 !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-3 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-4 div:first-of-type { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-4 div:nth-of-type(2) { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-4 div:first-of-type svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-4 div:nth-of-type(2) svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-5 div:first-of-type { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-5 div:nth-of-type(2) { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-5 div:first-of-type svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-5 div:nth-of-type(2) svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-date-today .wpsbc-legend-item-icon { border: 4px solid rgba( 33,150,243, .9 ) !important; }.wpsbc-container.wpsbc-calendar-1 .wpsbc-legend-item-icon-0 div:first-of-type { background-color: #e1e1e1 !important; }<\/style><div class=\"wpsbc-container-loaded\" data-just-loaded=\"1\"><\/div><\/div>\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-25 is-style-fill\"><a class=\"wp-block-button__link\" href=\"http:\/\/www.chambres-hote-aveyron.com\/index.php\/contact\/\">R\u00e9server<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chambre tout confort avec salle d&rsquo;eau.Double vasque et douche \u00e0 l&rsquo;italienne. Tarif : 60\u20ac \/ nuitPetit-d\u00e9jeuner : 10\u20acDiner : sur r\u00e9servation<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chambre Dune - Chez Vi<\/title>\n<meta name=\"description\" content=\"Chambres d&#039;h\u00f4tes dans l&#039;Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l&#039;a\u00e9roport.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chambre Dune - Chez Vi\" \/>\n<meta property=\"og:description\" content=\"Chambres d&#039;h\u00f4tes dans l&#039;Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l&#039;a\u00e9roport.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/\" \/>\n<meta property=\"og:site_name\" content=\"Chez Vi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chez.vi.chambres.hotes.aveyron\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T15:07:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/\",\"url\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/\",\"name\":\"Chambre Dune - Chez Vi\",\"isPartOf\":{\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg\",\"datePublished\":\"2021-08-14T13:28:08+00:00\",\"dateModified\":\"2022-07-26T15:07:41+00:00\",\"description\":\"Chambres d'h\u00f4tes dans l'Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l'a\u00e9roport.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage\",\"url\":\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg\",\"contentUrl\":\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg\",\"width\":720,\"height\":960,\"caption\":\"Chambre d'h\u00f4te. Proche de Rodez dans l'Aveyron\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.chambres-hote-aveyron.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chambre Dune\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#website\",\"url\":\"http:\/\/www.chambres-hote-aveyron.com\/\",\"name\":\"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron\",\"description\":\"Chambres d&#039;h\u00f4tes dans l&#039;Aveyron\",\"publisher\":{\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.chambres-hote-aveyron.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#organization\",\"name\":\"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron\",\"url\":\"http:\/\/www.chambres-hote-aveyron.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/cropped-cropped-logo1.png\",\"contentUrl\":\"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/cropped-cropped-logo1.png\",\"width\":512,\"height\":512,\"caption\":\"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron\"},\"image\":{\"@id\":\"http:\/\/www.chambres-hote-aveyron.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/chez.vi.chambres.hotes.aveyron\",\"https:\/\/www.instagram.com\/chambres_hote_aveyron\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chambre Dune - Chez Vi","description":"Chambres d'h\u00f4tes dans l'Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l'a\u00e9roport.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/","og_locale":"fr_FR","og_type":"article","og_title":"Chambre Dune - Chez Vi","og_description":"Chambres d'h\u00f4tes dans l'Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l'a\u00e9roport.","og_url":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/","og_site_name":"Chez Vi","article_publisher":"https:\/\/www.facebook.com\/chez.vi.chambres.hotes.aveyron","article_modified_time":"2022-07-26T15:07:41+00:00","og_image":[{"url":"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/","url":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/","name":"Chambre Dune - Chez Vi","isPartOf":{"@id":"http:\/\/www.chambres-hote-aveyron.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage"},"image":{"@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage"},"thumbnailUrl":"http:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg","datePublished":"2021-08-14T13:28:08+00:00","dateModified":"2022-07-26T15:07:41+00:00","description":"Chambres d'h\u00f4tes dans l'Aveyron, situ\u00e9 \u00e0 10 minutes de Rodez et de l'a\u00e9roport.","breadcrumb":{"@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#primaryimage","url":"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg","contentUrl":"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2022\/07\/dune2022-1.jpg","width":720,"height":960,"caption":"Chambre d'h\u00f4te. Proche de Rodez dans l'Aveyron"},{"@type":"BreadcrumbList","@id":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/chambre-dune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.chambres-hote-aveyron.com\/"},{"@type":"ListItem","position":2,"name":"Chambre Dune"}]},{"@type":"WebSite","@id":"http:\/\/www.chambres-hote-aveyron.com\/#website","url":"http:\/\/www.chambres-hote-aveyron.com\/","name":"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron","description":"Chambres d&#039;h\u00f4tes dans l&#039;Aveyron","publisher":{"@id":"http:\/\/www.chambres-hote-aveyron.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.chambres-hote-aveyron.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/www.chambres-hote-aveyron.com\/#organization","name":"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron","url":"http:\/\/www.chambres-hote-aveyron.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.chambres-hote-aveyron.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/cropped-cropped-logo1.png","contentUrl":"https:\/\/www.chambres-hote-aveyron.com\/wp-content\/uploads\/2021\/08\/cropped-cropped-logo1.png","width":512,"height":512,"caption":"Chez Vi - Chambres d'h\u00f4tes dans l'Aveyron"},"image":{"@id":"http:\/\/www.chambres-hote-aveyron.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chez.vi.chambres.hotes.aveyron","https:\/\/www.instagram.com\/chambres_hote_aveyron\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/pages\/61"}],"collection":[{"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":7,"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":1491,"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions\/1491"}],"wp:attachment":[{"href":"https:\/\/www.chambres-hote-aveyron.com\/index.php\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}